{"id":12205,"date":"2024-08-23T18:13:07","date_gmt":"2024-08-23T16:13:07","guid":{"rendered":"https:\/\/proseccoderiz.it\/?page_id=12205"},"modified":"2024-08-23T18:14:41","modified_gmt":"2024-08-23T16:14:41","slug":"shop-2","status":"publish","type":"page","link":"https:\/\/proseccoderiz.it\/en\/shop-2\/","title":{"rendered":"Shop"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12205\" class=\"elementor elementor-12205\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4591c0c e-flex e-con-boxed e-con e-parent\" data-id=\"4591c0c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb54994 elementor-widget elementor-widget-heading\" data-id=\"eb54994\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Shop<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-607510b e-flex e-con-boxed e-con e-parent\" data-id=\"607510b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b34441f e-con-full e-flex e-con e-child\" data-id=\"b34441f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e2c3f6 elementor-widget elementor-widget-heading\" data-id=\"3e2c3f6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">From white to red wines, passing through ros\u00e9 and the inevitable Prosecco Conegliano Valdobbiadene DOCG.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0dd3823 e-con-full elementor-hidden-desktop elementor-hidden-laptop e-flex e-con e-child\" data-id=\"0dd3823\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8b051d elementor-widget elementor-widget-woofilters\" data-id=\"b8b051d\" data-element_type=\"widget\" data-widget_type=\"woofilters.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-woofilters\"><style type=\"text\/css\" id=\"wpfCustomCss-2_75741\">#wpfMainWrapper-2_75741{position:relative;width:100%;}#wpfMainWrapper-2_75741 .wpfFilterWrapper {visibility:hidden;width:100%;}#wpfBlock_1 .wpfFilterVerScroll {max-height:200px;}#wpfMainWrapper-2_75741 .wpfLoaderLayout {position:absolute;top:0;bottom:0;left:0;right:0;background-color: rgba(255, 255, 255, 0.9);z-index: 999;}#wpfMainWrapper-2_75741 .wpfLoaderLayout i {position:absolute;z-index:9;top:50%;left:50%;margin-top:-30px;margin-left:-30px;color:rgba(0,0,0,.9);}<\/style><div class=\"wpfMainWrapper\" id=\"wpfMainWrapper-2_75741\" data-viewid=\"2_75741\" data-filter=\"2\" data-settings=\"{&quot;posts_per_page&quot;:16,&quot;posts_per_row&quot;:&quot;&quot;,&quot;paged&quot;:1,&quot;base&quot;:&quot;\\\/en\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/12205?product-page=%#%&quot;,&quot;format &quot;:&quot;?product-page=%#%&quot;,&quot;page_id&quot;:12205,&quot;paginate_base&quot;:&quot;page&quot;,&quot;paginate_type&quot;:&quot;url&quot;}\" data-default-query=\"\" data-filter-settings=\"{&quot;settings&quot;:{&quot;display_on_page&quot;:&quot;both&quot;,&quot;display_on_page_shortcode&quot;:&quot;0&quot;,&quot;display_for&quot;:&quot;both&quot;,&quot;force_show_current&quot;:&quot;0&quot;,&quot;desctop_mobile_breakpoint_switcher&quot;:&quot;1&quot;,&quot;desctop_mobile_breakpoint_width&quot;:&quot;1024&quot;,&quot;hide_without_products&quot;:&quot;0&quot;,&quot;count_product_shop&quot;:&quot;0&quot;,&quot;columns_product_shop&quot;:&quot;0&quot;,&quot;enable_ajax&quot;:&quot;1&quot;,&quot;remove_actions&quot;:&quot;0&quot;,&quot;display_status_private&quot;:&quot;0&quot;,&quot;product_list_selector&quot;:&quot;&quot;,&quot;product_container_selector&quot;:&quot;&quot;,&quot;force_theme_templates&quot;:&quot;0&quot;,&quot;recalculate_filters&quot;:&quot;0&quot;,&quot;no_redirect_by_no_products&quot;:&quot;0&quot;,&quot;do_not_use_shortcut&quot;:&quot;0&quot;,&quot;show_filtering_button&quot;:&quot;0&quot;,&quot;filtering_button_word&quot;:&quot;Filter&quot;,&quot;auto_update_filter&quot;:&quot;0&quot;,&quot;show_clean_button&quot;:&quot;0&quot;,&quot;show_clean_button_word&quot;:&quot;Clear&quot;,&quot;reset_all_filters&quot;:&quot;0&quot;,&quot;main_buttons_position&quot;:&quot;bottom&quot;,&quot;main_buttons_order&quot;:&quot;left&quot;,&quot;all_products_filtering&quot;:&quot;0&quot;,&quot;form_filter_by_all_products&quot;:&quot;0&quot;,&quot;show_clean_block&quot;:&quot;0&quot;,&quot;show_clean_block_word&quot;:&quot;Clear&quot;,&quot;filter_recount&quot;:&quot;0&quot;,&quot;filter_recount_price&quot;:&quot;0&quot;,&quot;keep_recount_price&quot;:&quot;0&quot;,&quot;filter_null_disabled&quot;:&quot;0&quot;,&quot;sort_by_title&quot;:&quot;0&quot;,&quot;checked_items_top&quot;:&quot;0&quot;,&quot;checked_items_bold&quot;:&quot;1&quot;,&quot;text_no_products&quot;:&quot;No products found&quot;,&quot;filtering_by_variations&quot;:&quot;1&quot;,&quot;form_filter_by_variations&quot;:&quot;0&quot;,&quot;exclude_backorder_variations&quot;:&quot;0&quot;,&quot;hide_filter_icon&quot;:&quot;1&quot;,&quot;use_title_as_slug&quot;:&quot;0&quot;,&quot;use_category_filtration&quot;:&quot;1&quot;,&quot;display_only_children_category&quot;:&quot;0&quot;,&quot;check_get_names&quot;:&quot;0&quot;,&quot;f_multi_logic&quot;:&quot;and&quot;,&quot;third_party_prefilter&quot;:&quot;0&quot;,&quot;filter_loader_icon_onload_enable&quot;:&quot;0&quot;,&quot;filter_loader_icon_color&quot;:&quot;#000000&quot;,&quot;filter_loader_icon_name&quot;:&quot;default&quot;,&quot;filter_loader_icon_number&quot;:&quot;0&quot;,&quot;enable_overlay&quot;:&quot;0&quot;,&quot;overlay_background&quot;:&quot;&quot;,&quot;enable_overlay_icon&quot;:&quot;0&quot;,&quot;enable_overlay_word&quot;:&quot;0&quot;,&quot;overlay_word&quot;:&quot;WooBeWoo&quot;,&quot;filter_width&quot;:&quot;100&quot;,&quot;filter_width_in&quot;:&quot;%&quot;,&quot;filter_width_mobile&quot;:&quot;100&quot;,&quot;filter_width_in_mobile&quot;:&quot;%&quot;,&quot;filter_block_width&quot;:&quot;100&quot;,&quot;filter_block_width_in&quot;:&quot;%&quot;,&quot;filter_block_width_mobile&quot;:&quot;100&quot;,&quot;filter_block_width_in_mobile&quot;:&quot;%&quot;,&quot;filter_block_height&quot;:&quot;&quot;,&quot;padding_child_list&quot;:&quot;&quot;,&quot;css_editor&quot;:&quot;&quot;,&quot;js_editor&quot;:&quot;&quot;,&quot;disable_fontawesome_loading&quot;:&quot;0&quot;,&quot;disable_plugin_styles&quot;:&quot;1&quot;,&quot;filters&quot;:{&quot;order&quot;:&quot;[{\\&quot;id\\&quot;:\\&quot;wpfCategory\\&quot;,\\&quot;uniqId\\&quot;:\\&quot;wpf_66c8a2e92e2dd\\&quot;,\\&quot;name\\&quot;:\\&quot;wpf_filter_cat\\&quot;,\\&quot;settings\\&quot;:{\\&quot;f_enable\\&quot;:true,\\&quot;f_title\\&quot;:\\&quot;Categories\\&quot;,\\&quot;f_name\\&quot;:\\&quot;Product categories\\&quot;,\\&quot;f_enable_title\\&quot;:\\&quot;yes_open\\&quot;,\\&quot;f_enable_title_mobile\\&quot;:\\&quot;yes_close\\&quot;,\\&quot;f_frontend_type\\&quot;:\\&quot;list\\&quot;,\\&quot;f_show_hierarchical\\&quot;:false,\\&quot;f_hide_parent\\&quot;:false,\\&quot;f_multi_logic_hierarchical\\&quot;:\\&quot;any\\&quot;,\\&quot;f_extend_parent_filtering\\&quot;:true,\\&quot;f_custom_tags\\&quot;:false,\\&quot;f_custom_tags_settings[header]\\&quot;:\\&quot;0\\&quot;,\\&quot;f_custom_tags_settings[title_1]\\&quot;:\\&quot;0\\&quot;,\\&quot;f_custom_tags_settings[title_2]\\&quot;:\\&quot;0\\&quot;,\\&quot;f_custom_tags_settings[title_3]\\&quot;:\\&quot;0\\&quot;,\\&quot;f_sort_by\\&quot;:\\&quot;desc\\&quot;,\\&quot;f_order_custom\\&quot;:false,\\&quot;f_show_count\\&quot;:true,\\&quot;f_show_count_parent_with_children\\&quot;:false,\\&quot;f_hide_empty\\&quot;:false,\\&quot;f_hide_empty_active\\&quot;:false,\\&quot;f_mlist[]\\&quot;:\\&quot;\\&quot;,\\&quot;f_mlist_with_children\\&quot;:false,\\&quot;f_hidden_categories\\&quot;:false,\\&quot;f_filtered_by_selected\\&quot;:false,\\&quot;f_show_search_input\\&quot;:false,\\&quot;f_unfolding_by_search\\&quot;:false,\\&quot;f_collapse_by_delete\\&quot;:false,\\&quot;f_hide_taxonomy\\&quot;:false,\\&quot;f_show_all_categories\\&quot;:false,\\&quot;f_layout\\&quot;:\\&quot;ver\\&quot;,\\&quot;f_ver_columns\\&quot;:\\&quot;1\\&quot;,\\&quot;f_max_height\\&quot;:\\&quot;200\\&quot;}}]&quot;,&quot;preselect&quot;:&quot;&quot;}}}\" data-nowoo=\"true\"><div class=\"wpfFilterWrapper wpfNotActive wpfShowCount\" id=\"wpfBlock_1\" data-order-key=\"0\"  data-filter-type=\"wpfCategory\" data-get-attribute=\"wpf_filter_cat_0\" data-display-type=\"list\" data-content-type=\"taxonomy\" data-slug=\"category\" data-uniq-id=\"wpf_66c8a2e92e2dd\" data-radio=\"1\" data-query-logic=\"or\" data-logic-hierarchical=\"any\" data-query-children=\"1\" data-show-hierarchical=\"false\" data-taxonomy=\"product_cat\" data-hide-active=\"0\" data-show-all=\"0\" data-use-slugs=\"0\"><div class=\"wpfFilterTitle\"  data-show-on-mobile=\"yes_close\" data-show-on-desctop=\"yes_open\" ><div class=\"wfpTitle wfpClickable\">Categories<\/div><i class=\"fa fa-minus wpfTitleToggle\"><\/i><\/div><div class=\"wpfFilterContent\"><div class=\"wpfCheckboxHier\"><ul class=\"wpfFilterVerScroll\"><li data-term-id=\"51\" data-parent=\"0\" data-term-slug=\"white-wines\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox5195028\" ><label aria-label=\"White wines\" for=\"wpfTaxonomyInputCheckbox5195028\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">White wines<\/span><\/span><span class=\"wpfCount\">(11)<\/span><\/span><\/label><\/li><li data-term-id=\"55\" data-parent=\"0\" data-term-slug=\"tastings\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox5595004\" ><label aria-label=\"Tastings\" for=\"wpfTaxonomyInputCheckbox5595004\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Tastings<\/span><\/span><span class=\"wpfCount\">(3)<\/span><\/span><\/label><\/li><li data-term-id=\"73\" data-parent=\"0\" data-term-slug=\"still-wines\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox732208\" ><label aria-label=\"Still wines\" for=\"wpfTaxonomyInputCheckbox732208\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Still wines<\/span><\/span><span class=\"wpfCount\">(4)<\/span><\/span><\/label><\/li><li data-term-id=\"54\" data-parent=\"0\" data-term-slug=\"sparkling-wines\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox546711\" ><label aria-label=\"Sparkling wines\" for=\"wpfTaxonomyInputCheckbox546711\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Sparkling wines<\/span><\/span><span class=\"wpfCount\">(8)<\/span><\/span><\/label><\/li><li data-term-id=\"72\" data-parent=\"0\" data-term-slug=\"semi-sparkling-wines\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox7269158\" ><label aria-label=\"Semi-sparkling wines\" for=\"wpfTaxonomyInputCheckbox7269158\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Semi-sparkling wines<\/span><\/span><span class=\"wpfCount\">(3)<\/span><\/span><\/label><\/li><li data-term-id=\"52\" data-parent=\"0\" data-term-slug=\"rose-en\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox5273277\" ><label aria-label=\"Ros\u00e9\" for=\"wpfTaxonomyInputCheckbox5273277\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Ros\u00e9<\/span><\/span><span class=\"wpfCount\">(2)<\/span><\/span><\/label><\/li><li data-term-id=\"50\" data-parent=\"0\" data-term-slug=\"red-wines\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox5051037\" ><label aria-label=\"Red wines\" for=\"wpfTaxonomyInputCheckbox5051037\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Red wines<\/span><\/span><span class=\"wpfCount\">(2)<\/span><\/span><\/label><\/li><li data-term-id=\"48\" data-parent=\"0\" data-term-slug=\"magnum-en\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox4879669\" ><label aria-label=\"Magnum\" for=\"wpfTaxonomyInputCheckbox4879669\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Magnum<\/span><\/span><span class=\"wpfCount\">(2)<\/span><\/span><\/label><\/li><li data-term-id=\"49\" data-parent=\"0\" data-term-slug=\"le-val-en\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox4958354\" ><label aria-label=\"Le Val\" for=\"wpfTaxonomyInputCheckbox4958354\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Le Val<\/span><\/span><span class=\"wpfCount\">(4)<\/span><\/span><\/label><\/li><li data-term-id=\"56\" data-parent=\"0\" data-term-slug=\"gift-cards\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox5632632\" ><label aria-label=\"Gift cards\" for=\"wpfTaxonomyInputCheckbox5632632\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Gift cards<\/span><\/span><span class=\"wpfCount\">(1)<\/span><\/span><\/label><\/li><li data-term-id=\"53\" data-parent=\"0\" data-term-slug=\"docg-en\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox5321960\" ><label aria-label=\"DOCG\" for=\"wpfTaxonomyInputCheckbox5321960\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">DOCG<\/span><\/span><span class=\"wpfCount\">(5)<\/span><\/span><\/label><\/li><\/ul><\/div><\/div><\/div><div class=\"wpfLoaderLayout\"><i class=\"fa fa-spinner fa-pulse fa-3x fa-fw\"><\/i><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f481a4e elementor-grid-3 elementor-grid-mobile_extra-2 elementor-grid-mobile-1 elementor-product-loop-item--align-center elementor-grid-tablet-3 elementor-products-grid elementor-wc-products elementor-widget elementor-widget-woocommerce-products\" data-id=\"f481a4e\" data-element_type=\"widget\" data-widget_type=\"woocommerce-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce columns-3 \"><span class=\"wpfHidden\" data-shortcode-attribute=\"{&quot;limit&quot;:&quot;-1&quot;,&quot;columns&quot;:3,&quot;rows&quot;:20,&quot;orderby&quot;:&quot;&quot;,&quot;order&quot;:&quot;&quot;,&quot;ids&quot;:&quot;&quot;,&quot;skus&quot;:&quot;&quot;,&quot;category&quot;:&quot;&quot;,&quot;cat_operator&quot;:&quot;IN&quot;,&quot;attribute&quot;:&quot;&quot;,&quot;terms&quot;:&quot;&quot;,&quot;terms_operator&quot;:&quot;IN&quot;,&quot;tag&quot;:&quot;&quot;,&quot;tag_operator&quot;:&quot;IN&quot;,&quot;visibility&quot;:&quot;visible&quot;,&quot;class&quot;:&quot;&quot;,&quot;page&quot;:1,&quot;paginate&quot;:&quot;&quot;,&quot;cache&quot;:false}\"><\/span><ul class=\"products elementor-grid columns-3\">\n<li class=\"product type-product post-12170 status-publish first instock product_cat-docg-en product_cat-sparkling-wines product_cat-white-wines has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/caris\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-docg-extra-brut-caris-de-riz.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-docg-extra-brut-caris-de-riz.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-docg-extra-brut-caris-de-riz-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-docg-extra-brut-caris-de-riz-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-docg-extra-brut-caris-de-riz-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Caris<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tConegliano Valdobbiadene Prosecco Superiore DOCG Extra Brut\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>12,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12170\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12171 status-publish instock product_cat-docg-en product_cat-sparkling-wines product_cat-white-wines has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/costaderu\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-superiore-docg-brut-costaderu-de-riz.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-superiore-docg-brut-costaderu-de-riz.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-superiore-docg-brut-costaderu-de-riz-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-superiore-docg-brut-costaderu-de-riz-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-superiore-docg-brut-costaderu-de-riz-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Costader\u00f9<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tConegliano Valdobbiadene Prosecco Superiore DOCG Brut\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>10,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12171\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12165 status-publish last instock product_cat-docg-en product_cat-sparkling-wines product_cat-white-wines has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/nonno-carlo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-spumante-docg-brut-millesimato-nonno-carlo-de-riz.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-spumante-docg-brut-millesimato-nonno-carlo-de-riz.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-spumante-docg-brut-millesimato-nonno-carlo-de-riz-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-spumante-docg-brut-millesimato-nonno-carlo-de-riz-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-spumante-docg-brut-millesimato-nonno-carlo-de-riz-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Nonno Carlo<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tConegliano Valdobbiadene Prosecco Superiore DOCG Brut Millesimato 2025\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>12,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12165\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12172 status-publish first instock product_cat-docg-en product_cat-sparkling-wines product_cat-white-wines has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/costabea\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t<span class=\"onsale\">Sconto 15%<\/span>\n\t<div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-superiore-docg-extra-dry-costabea-de-riz.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-superiore-docg-extra-dry-costabea-de-riz.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-superiore-docg-extra-dry-costabea-de-riz-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-superiore-docg-extra-dry-costabea-de-riz-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/prosecco-superiore-docg-extra-dry-costabea-de-riz-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Costabea<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tConegliano Valdobbiadene Prosecco Superiore DOCG Extra Dry\t<\/div>\n\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>10,00<\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Original price was: &euro;10,00.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>8,50<\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Current price is: &euro;8,50.<\/span><\/span>\n<\/a><a href=\"?add-to-cart=12172\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12167 status-publish instock product_cat-rose-en product_cat-sparkling-wines has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/gioia\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-gioia.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-gioia.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-gioia-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-gioia-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-gioia-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Gioia<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tManzoni Moscato 13.0.25\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>8,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12167\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12841 status-publish last instock product_cat-sparkling-wines product_cat-white-wines has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/3note\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/10\/3note-cuvee-de-riz.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/10\/3note-cuvee-de-riz.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/10\/3note-cuvee-de-riz-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/10\/3note-cuvee-de-riz-396x1024.png 396w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/10\/3note-cuvee-de-riz-300x776.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">3note<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tCuv\u00e9e Brut\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>7,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12841\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12163 status-publish first outofstock product_cat-docg-en product_cat-magnum-en product_cat-sparkling-wines product_cat-white-wines has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/costaderu-magnum\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-costaderu_magnum.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-costaderu_magnum.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-costaderu_magnum-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-costaderu_magnum-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-costaderu_magnum-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Costader\u00f9 Magnum<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tConegliano Valdobbiadene DOCG Brut\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>23,00<\/bdi><\/span><\/span>\n<\/a><a href=\"https:\/\/proseccoderiz.it\/en\/product\/costaderu-magnum\/\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12169 status-publish instock product_cat-magnum-en product_cat-sparkling-wines product_cat-white-wines has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/feston-magnum\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">\n\t<span class=\"onsale\">Sconto 15%<\/span>\n\t<div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-feston_magnum.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-feston_magnum.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-feston_magnum-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-feston_magnum-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-feston_magnum-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Fest&#8217;on Magnum<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tExtra Dry\t<\/div>\n\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15,00<\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Original price was: &euro;15,00.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>12,75<\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Current price is: &euro;12,75.<\/span><\/span>\n<\/a><a href=\"?add-to-cart=12169\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12168 status-publish last instock product_cat-semi-sparkling-wines product_cat-white-wines has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/fondi\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-frizzante-fondi-de-riz.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-frizzante-fondi-de-riz.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-frizzante-fondi-de-riz-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-frizzante-fondi-de-riz-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-frizzante-fondi-de-riz-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Fond\u00ec<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tSemi-sparkling white wine\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>7,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12168\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12166 status-publish first instock product_cat-semi-sparkling-wines product_cat-white-wines has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/matthaeus\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-frizzante-matthaeus-de-riz.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-frizzante-matthaeus-de-riz.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-frizzante-matthaeus-de-riz-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-frizzante-matthaeus-de-riz-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-frizzante-matthaeus-de-riz-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Matthaeus<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tSemi-sparkling white wine\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>8,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12166\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12164 status-publish outofstock product_cat-rose-en product_cat-semi-sparkling-wines has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/rosi\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosato-rose-frizzante-rosi-de-riz.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosato-rose-frizzante-rosi-de-riz.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosato-rose-frizzante-rosi-de-riz-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosato-rose-frizzante-rosi-de-riz-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosato-rose-frizzante-rosi-de-riz-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Ros\u00ec<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tSemi-sparkling ros\u00e9\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>7,00<\/bdi><\/span><\/span>\n<\/a><a href=\"https:\/\/proseccoderiz.it\/en\/product\/rosi\/\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12173 status-publish last instock product_cat-le-val-en product_cat-still-wines product_cat-white-wines has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/le-val-chardonnay\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-fermo-igt-le-val-chardonnay-de-riz.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-fermo-igt-le-val-chardonnay-de-riz.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-fermo-igt-le-val-chardonnay-de-riz-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-fermo-igt-le-val-chardonnay-de-riz-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-fermo-igt-le-val-chardonnay-de-riz-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Le Val Chardonnay<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tIGT Marca trevigiana\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>9,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12173\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12175 status-publish first instock product_cat-le-val-en product_cat-still-wines product_cat-white-wines has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/le-val-bianco\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-fermo-igt-le-val-de-riz.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-fermo-igt-le-val-de-riz.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-fermo-igt-le-val-de-riz-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-fermo-igt-le-val-de-riz-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-bianco-fermo-igt-le-val-de-riz-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Le Val Bianco<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tIGT Marca trevigiana\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>7,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12175\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12174 status-publish instock product_cat-le-val-en product_cat-red-wines product_cat-still-wines has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/le-val-rosso-barrique\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosso-igt-leval-barrique-de-riz.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosso-igt-leval-barrique-de-riz.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosso-igt-leval-barrique-de-riz-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosso-igt-leval-barrique-de-riz-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosso-igt-leval-barrique-de-riz-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Le Val Rosso Barrique<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tIGT Marca trevigiana\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>9,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12174\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12176 status-publish last instock product_cat-le-val-en product_cat-red-wines product_cat-still-wines has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/le-val-rosso\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"1035\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosso-igt-leval-de-riz.png\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosso-igt-leval-de-riz.png 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosso-igt-leval-de-riz-300x776.png 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosso-igt-leval-de-riz-116x300.png 116w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/vino-rosso-igt-leval-de-riz-396x1024.png 396w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Le Val Rosso<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tIGT Marca trevigiana\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>7,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12176\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12157 status-publish first instock product_cat-tastings has-post-thumbnail virtual taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/experience-coupon-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"560\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/degustazione1.jpg\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/degustazione1.jpg 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/degustazione1-300x420.jpg 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/degustazione1-214x300.jpg 214w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Experience coupon<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tDiscovering the Conegliano Valdobbiadene\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12157\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12158 status-publish instock product_cat-tastings has-post-thumbnail virtual taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/experience-coupon-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"560\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/degustazione2.jpg\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/degustazione2.jpg 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/degustazione2-300x420.jpg 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/degustazione2-214x300.jpg 214w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Experience coupon<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tCompairing bubbles\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>28,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12158\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12159 status-publish last instock product_cat-tastings has-post-thumbnail virtual taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/experience-coupon\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"560\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/degustazione3.jpg\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/degustazione3.jpg 400w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/degustazione3-300x420.jpg 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/degustazione3-214x300.jpg 214w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Experience coupon<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\tA Wine for every Occasion\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>35,00<\/bdi><\/span><\/span>\n<\/a><a href=\"?add-to-cart=12159\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<li class=\"product type-product post-12156 status-publish first instock product_cat-gift-cards has-post-thumbnail purchasable product-type-variable has-default-attributes\">\n\t<a href=\"https:\/\/proseccoderiz.it\/en\/product\/gift-card\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"custom-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"402\" height=\"560\" src=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/buono.jpg\" class=\"attachment-my-custom-size size-my-custom-size\" alt=\"\" srcset=\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/buono.jpg 402w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/buono-300x418.jpg 300w, https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/buono-215x300.jpg 215w\" sizes=\"(max-width: 402px) 100vw, 402px\" \/><\/div><h2 class=\"woocommerce-loop-product__title\">Gift card<\/h2>\t<div itemprop=\"description\" class=\"product-subtitle\">\n\t\t\t<\/div>\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>30,00<\/bdi><\/span> &ndash; <span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>100,00<\/bdi><\/span><\/span>\n<\/a><a href=\"https:\/\/proseccoderiz.it\/en\/product\/gift-card\/\" class=\"button add_to_cart_button custom-add-to-cart\"><img decoding=\"async\" src=\"http:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/basket-black.svg\" alt=\"Add to Cart\" \/><\/a><\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a0d91d e-con-full elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra e-flex e-con e-child\" data-id=\"3a0d91d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6080335 elementor-widget elementor-widget-woofilters\" data-id=\"6080335\" data-element_type=\"widget\" data-widget_type=\"woofilters.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-woofilters\"><style type=\"text\/css\" id=\"wpfCustomCss-2_216553\">#wpfMainWrapper-2_216553{position:relative;width:100%;}#wpfMainWrapper-2_216553 .wpfFilterWrapper {visibility:hidden;width:100%;}#wpfBlock_2 .wpfFilterVerScroll {max-height:200px;}#wpfMainWrapper-2_216553 .wpfLoaderLayout {position:absolute;top:0;bottom:0;left:0;right:0;background-color: rgba(255, 255, 255, 0.9);z-index: 999;}#wpfMainWrapper-2_216553 .wpfLoaderLayout i {position:absolute;z-index:9;top:50%;left:50%;margin-top:-30px;margin-left:-30px;color:rgba(0,0,0,.9);}<\/style><div class=\"wpfMainWrapper\" id=\"wpfMainWrapper-2_216553\" data-viewid=\"2_216553\" data-filter=\"2\" data-settings=\"{&quot;posts_per_page&quot;:16,&quot;posts_per_row&quot;:&quot;&quot;,&quot;paged&quot;:1,&quot;base&quot;:&quot;https:\\\/\\\/proseccoderiz.it\\\/en\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/12205\\\/page\\\/%#%\\\/&quot;,&quot;format &quot;:&quot;&quot;,&quot;page_id&quot;:12205,&quot;paginate_base&quot;:&quot;page&quot;,&quot;paginate_type&quot;:&quot;url&quot;}\" data-default-query=\"\" data-filter-settings=\"{&quot;settings&quot;:{&quot;display_on_page&quot;:&quot;both&quot;,&quot;display_on_page_shortcode&quot;:&quot;0&quot;,&quot;display_for&quot;:&quot;both&quot;,&quot;force_show_current&quot;:&quot;0&quot;,&quot;desctop_mobile_breakpoint_switcher&quot;:&quot;1&quot;,&quot;desctop_mobile_breakpoint_width&quot;:&quot;1024&quot;,&quot;hide_without_products&quot;:&quot;0&quot;,&quot;count_product_shop&quot;:&quot;0&quot;,&quot;columns_product_shop&quot;:&quot;0&quot;,&quot;enable_ajax&quot;:&quot;1&quot;,&quot;remove_actions&quot;:&quot;0&quot;,&quot;display_status_private&quot;:&quot;0&quot;,&quot;product_list_selector&quot;:&quot;&quot;,&quot;product_container_selector&quot;:&quot;&quot;,&quot;force_theme_templates&quot;:&quot;0&quot;,&quot;recalculate_filters&quot;:&quot;0&quot;,&quot;no_redirect_by_no_products&quot;:&quot;0&quot;,&quot;do_not_use_shortcut&quot;:&quot;0&quot;,&quot;show_filtering_button&quot;:&quot;0&quot;,&quot;filtering_button_word&quot;:&quot;Filter&quot;,&quot;auto_update_filter&quot;:&quot;0&quot;,&quot;show_clean_button&quot;:&quot;0&quot;,&quot;show_clean_button_word&quot;:&quot;Clear&quot;,&quot;reset_all_filters&quot;:&quot;0&quot;,&quot;main_buttons_position&quot;:&quot;bottom&quot;,&quot;main_buttons_order&quot;:&quot;left&quot;,&quot;all_products_filtering&quot;:&quot;0&quot;,&quot;form_filter_by_all_products&quot;:&quot;0&quot;,&quot;show_clean_block&quot;:&quot;0&quot;,&quot;show_clean_block_word&quot;:&quot;Clear&quot;,&quot;filter_recount&quot;:&quot;0&quot;,&quot;filter_recount_price&quot;:&quot;0&quot;,&quot;keep_recount_price&quot;:&quot;0&quot;,&quot;filter_null_disabled&quot;:&quot;0&quot;,&quot;sort_by_title&quot;:&quot;0&quot;,&quot;checked_items_top&quot;:&quot;0&quot;,&quot;checked_items_bold&quot;:&quot;1&quot;,&quot;text_no_products&quot;:&quot;No products found&quot;,&quot;filtering_by_variations&quot;:&quot;1&quot;,&quot;form_filter_by_variations&quot;:&quot;0&quot;,&quot;exclude_backorder_variations&quot;:&quot;0&quot;,&quot;hide_filter_icon&quot;:&quot;1&quot;,&quot;use_title_as_slug&quot;:&quot;0&quot;,&quot;use_category_filtration&quot;:&quot;1&quot;,&quot;display_only_children_category&quot;:&quot;0&quot;,&quot;check_get_names&quot;:&quot;0&quot;,&quot;f_multi_logic&quot;:&quot;and&quot;,&quot;third_party_prefilter&quot;:&quot;0&quot;,&quot;filter_loader_icon_onload_enable&quot;:&quot;0&quot;,&quot;filter_loader_icon_color&quot;:&quot;#000000&quot;,&quot;filter_loader_icon_name&quot;:&quot;default&quot;,&quot;filter_loader_icon_number&quot;:&quot;0&quot;,&quot;enable_overlay&quot;:&quot;0&quot;,&quot;overlay_background&quot;:&quot;&quot;,&quot;enable_overlay_icon&quot;:&quot;0&quot;,&quot;enable_overlay_word&quot;:&quot;0&quot;,&quot;overlay_word&quot;:&quot;WooBeWoo&quot;,&quot;filter_width&quot;:&quot;100&quot;,&quot;filter_width_in&quot;:&quot;%&quot;,&quot;filter_width_mobile&quot;:&quot;100&quot;,&quot;filter_width_in_mobile&quot;:&quot;%&quot;,&quot;filter_block_width&quot;:&quot;100&quot;,&quot;filter_block_width_in&quot;:&quot;%&quot;,&quot;filter_block_width_mobile&quot;:&quot;100&quot;,&quot;filter_block_width_in_mobile&quot;:&quot;%&quot;,&quot;filter_block_height&quot;:&quot;&quot;,&quot;padding_child_list&quot;:&quot;&quot;,&quot;css_editor&quot;:&quot;&quot;,&quot;js_editor&quot;:&quot;&quot;,&quot;disable_fontawesome_loading&quot;:&quot;0&quot;,&quot;disable_plugin_styles&quot;:&quot;1&quot;,&quot;filters&quot;:{&quot;order&quot;:&quot;[{\\&quot;id\\&quot;:\\&quot;wpfCategory\\&quot;,\\&quot;uniqId\\&quot;:\\&quot;wpf_66c8a2e92e2dd\\&quot;,\\&quot;name\\&quot;:\\&quot;wpf_filter_cat\\&quot;,\\&quot;settings\\&quot;:{\\&quot;f_enable\\&quot;:true,\\&quot;f_title\\&quot;:\\&quot;Categories\\&quot;,\\&quot;f_name\\&quot;:\\&quot;Product categories\\&quot;,\\&quot;f_enable_title\\&quot;:\\&quot;yes_open\\&quot;,\\&quot;f_enable_title_mobile\\&quot;:\\&quot;yes_close\\&quot;,\\&quot;f_frontend_type\\&quot;:\\&quot;list\\&quot;,\\&quot;f_show_hierarchical\\&quot;:false,\\&quot;f_hide_parent\\&quot;:false,\\&quot;f_multi_logic_hierarchical\\&quot;:\\&quot;any\\&quot;,\\&quot;f_extend_parent_filtering\\&quot;:true,\\&quot;f_custom_tags\\&quot;:false,\\&quot;f_custom_tags_settings[header]\\&quot;:\\&quot;0\\&quot;,\\&quot;f_custom_tags_settings[title_1]\\&quot;:\\&quot;0\\&quot;,\\&quot;f_custom_tags_settings[title_2]\\&quot;:\\&quot;0\\&quot;,\\&quot;f_custom_tags_settings[title_3]\\&quot;:\\&quot;0\\&quot;,\\&quot;f_sort_by\\&quot;:\\&quot;desc\\&quot;,\\&quot;f_order_custom\\&quot;:false,\\&quot;f_show_count\\&quot;:true,\\&quot;f_show_count_parent_with_children\\&quot;:false,\\&quot;f_hide_empty\\&quot;:false,\\&quot;f_hide_empty_active\\&quot;:false,\\&quot;f_mlist[]\\&quot;:\\&quot;\\&quot;,\\&quot;f_mlist_with_children\\&quot;:false,\\&quot;f_hidden_categories\\&quot;:false,\\&quot;f_filtered_by_selected\\&quot;:false,\\&quot;f_show_search_input\\&quot;:false,\\&quot;f_unfolding_by_search\\&quot;:false,\\&quot;f_collapse_by_delete\\&quot;:false,\\&quot;f_hide_taxonomy\\&quot;:false,\\&quot;f_show_all_categories\\&quot;:false,\\&quot;f_layout\\&quot;:\\&quot;ver\\&quot;,\\&quot;f_ver_columns\\&quot;:\\&quot;1\\&quot;,\\&quot;f_max_height\\&quot;:\\&quot;200\\&quot;}}]&quot;,&quot;preselect&quot;:&quot;&quot;}}}\" data-nowoo=\"true\"><div class=\"wpfFilterWrapper wpfNotActive wpfShowCount\" id=\"wpfBlock_2\" data-order-key=\"0\"  data-filter-type=\"wpfCategory\" data-get-attribute=\"wpf_filter_cat_0\" data-display-type=\"list\" data-content-type=\"taxonomy\" data-slug=\"category\" data-uniq-id=\"wpf_66c8a2e92e2dd\" data-radio=\"1\" data-query-logic=\"or\" data-logic-hierarchical=\"any\" data-query-children=\"1\" data-show-hierarchical=\"false\" data-taxonomy=\"product_cat\" data-hide-active=\"0\" data-show-all=\"0\" data-use-slugs=\"0\"><div class=\"wpfFilterTitle\"  data-show-on-mobile=\"yes_close\" data-show-on-desctop=\"yes_open\" ><div class=\"wfpTitle wfpClickable\">Categories<\/div><i class=\"fa fa-minus wpfTitleToggle\"><\/i><\/div><div class=\"wpfFilterContent\"><div class=\"wpfCheckboxHier\"><ul class=\"wpfFilterVerScroll\"><li data-term-id=\"51\" data-parent=\"0\" data-term-slug=\"white-wines\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox5188344\" ><label aria-label=\"White wines\" for=\"wpfTaxonomyInputCheckbox5188344\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">White wines<\/span><\/span><span class=\"wpfCount\">(11)<\/span><\/span><\/label><\/li><li data-term-id=\"55\" data-parent=\"0\" data-term-slug=\"tastings\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox5527451\" ><label aria-label=\"Tastings\" for=\"wpfTaxonomyInputCheckbox5527451\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Tastings<\/span><\/span><span class=\"wpfCount\">(3)<\/span><\/span><\/label><\/li><li data-term-id=\"73\" data-parent=\"0\" data-term-slug=\"still-wines\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox7371769\" ><label aria-label=\"Still wines\" for=\"wpfTaxonomyInputCheckbox7371769\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Still wines<\/span><\/span><span class=\"wpfCount\">(4)<\/span><\/span><\/label><\/li><li data-term-id=\"54\" data-parent=\"0\" data-term-slug=\"sparkling-wines\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox5485368\" ><label aria-label=\"Sparkling wines\" for=\"wpfTaxonomyInputCheckbox5485368\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Sparkling wines<\/span><\/span><span class=\"wpfCount\">(8)<\/span><\/span><\/label><\/li><li data-term-id=\"72\" data-parent=\"0\" data-term-slug=\"semi-sparkling-wines\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox7285228\" ><label aria-label=\"Semi-sparkling wines\" for=\"wpfTaxonomyInputCheckbox7285228\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Semi-sparkling wines<\/span><\/span><span class=\"wpfCount\">(3)<\/span><\/span><\/label><\/li><li data-term-id=\"52\" data-parent=\"0\" data-term-slug=\"rose-en\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox5242297\" ><label aria-label=\"Ros\u00e9\" for=\"wpfTaxonomyInputCheckbox5242297\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Ros\u00e9<\/span><\/span><span class=\"wpfCount\">(2)<\/span><\/span><\/label><\/li><li data-term-id=\"50\" data-parent=\"0\" data-term-slug=\"red-wines\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox5026084\" ><label aria-label=\"Red wines\" for=\"wpfTaxonomyInputCheckbox5026084\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Red wines<\/span><\/span><span class=\"wpfCount\">(2)<\/span><\/span><\/label><\/li><li data-term-id=\"48\" data-parent=\"0\" data-term-slug=\"magnum-en\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox4846665\" ><label aria-label=\"Magnum\" for=\"wpfTaxonomyInputCheckbox4846665\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Magnum<\/span><\/span><span class=\"wpfCount\">(2)<\/span><\/span><\/label><\/li><li data-term-id=\"49\" data-parent=\"0\" data-term-slug=\"le-val-en\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox4943815\" ><label aria-label=\"Le Val\" for=\"wpfTaxonomyInputCheckbox4943815\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Le Val<\/span><\/span><span class=\"wpfCount\">(4)<\/span><\/span><\/label><\/li><li data-term-id=\"56\" data-parent=\"0\" data-term-slug=\"gift-cards\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox5685503\" ><label aria-label=\"Gift cards\" for=\"wpfTaxonomyInputCheckbox5685503\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">Gift cards<\/span><\/span><span class=\"wpfCount\">(1)<\/span><\/span><\/label><\/li><li data-term-id=\"53\" data-parent=\"0\" data-term-slug=\"docg-en\"><label class=\"wpfLiLabel\"><span class=\"wpfCheckbox\"><input type=\"checkbox\" id=\"wpfTaxonomyInputCheckbox5325794\" ><label aria-label=\"DOCG\" for=\"wpfTaxonomyInputCheckbox5325794\"><\/label><\/span><span class=\"wpfDisplay\"><span class=\"wpfValue\"><span class=\"wpfFilterTaxNameWrapper\">DOCG<\/span><\/span><span class=\"wpfCount\">(5)<\/span><\/span><\/label><\/li><\/ul><\/div><\/div><\/div><div class=\"wpfLoaderLayout\"><i class=\"fa fa-spinner fa-pulse fa-3x fa-fw\"><\/i><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Shop From white to red wines, passing through ros\u00e9 and the inevitable Prosecco Conegliano Valdobbiadene DOCG. Categories White wines(8) Tastings(3) Sparkling wines(6) Ros\u00e9(0) Red wines(2) Magnum(0) Le Val(0) Gift cards(1) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-12205","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Shop - De Riz Prosecco - Cantina in Conegliano Valdobbiadene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proseccoderiz.it\/negozio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shop - De Riz Prosecco - Cantina in Conegliano Valdobbiadene\" \/>\n<meta property=\"og:description\" content=\"Shop From white to red wines, passing through ros\u00e9 and the inevitable Prosecco Conegliano Valdobbiadene DOCG. Categories White wines(8) Tastings(3) Sparkling wines(6) Ros\u00e9(0) Red wines(2) Magnum(0) Le Val(0) Gift cards(1) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proseccoderiz.it\/negozio\/\" \/>\n<meta property=\"og:site_name\" content=\"De Riz Prosecco - Cantina in Conegliano Valdobbiadene\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-23T16:14:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/proseccoderiz.it\/negozio\/\",\"url\":\"https:\/\/proseccoderiz.it\/negozio\/\",\"name\":\"Shop - De Riz Prosecco - Cantina in Conegliano Valdobbiadene\",\"isPartOf\":{\"@id\":\"https:\/\/proseccoderiz.it\/#website\"},\"datePublished\":\"2024-08-23T16:13:07+00:00\",\"dateModified\":\"2024-08-23T16:14:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/proseccoderiz.it\/negozio\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/proseccoderiz.it\/negozio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/proseccoderiz.it\/negozio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/proseccoderiz.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/proseccoderiz.it\/#website\",\"url\":\"https:\/\/proseccoderiz.it\/\",\"name\":\"De Riz Prosecco - Cantina in Conegliano Valdobbiadene\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/proseccoderiz.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/proseccoderiz.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/proseccoderiz.it\/#organization\",\"name\":\"De Riz Prosecco - Cantina in Conegliano Valdobbiadene\",\"url\":\"https:\/\/proseccoderiz.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/proseccoderiz.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/logo-1.png\",\"contentUrl\":\"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/logo-1.png\",\"width\":494,\"height\":313,\"caption\":\"De Riz Prosecco - Cantina in Conegliano Valdobbiadene\"},\"image\":{\"@id\":\"https:\/\/proseccoderiz.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shop - De Riz Prosecco - Cantina in Conegliano Valdobbiadene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proseccoderiz.it\/negozio\/","og_locale":"en_US","og_type":"article","og_title":"Shop - De Riz Prosecco - Cantina in Conegliano Valdobbiadene","og_description":"Shop From white to red wines, passing through ros\u00e9 and the inevitable Prosecco Conegliano Valdobbiadene DOCG. Categories White wines(8) Tastings(3) Sparkling wines(6) Ros\u00e9(0) Red wines(2) Magnum(0) Le Val(0) Gift cards(1) [&hellip;]","og_url":"https:\/\/proseccoderiz.it\/negozio\/","og_site_name":"De Riz Prosecco - Cantina in Conegliano Valdobbiadene","article_modified_time":"2024-08-23T16:14:41+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/proseccoderiz.it\/negozio\/","url":"https:\/\/proseccoderiz.it\/negozio\/","name":"Shop - De Riz Prosecco - Cantina in Conegliano Valdobbiadene","isPartOf":{"@id":"https:\/\/proseccoderiz.it\/#website"},"datePublished":"2024-08-23T16:13:07+00:00","dateModified":"2024-08-23T16:14:41+00:00","breadcrumb":{"@id":"https:\/\/proseccoderiz.it\/negozio\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proseccoderiz.it\/negozio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/proseccoderiz.it\/negozio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/proseccoderiz.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop"}]},{"@type":"WebSite","@id":"https:\/\/proseccoderiz.it\/#website","url":"https:\/\/proseccoderiz.it\/","name":"De Riz Prosecco - Cantina in Conegliano Valdobbiadene","description":"","publisher":{"@id":"https:\/\/proseccoderiz.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proseccoderiz.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proseccoderiz.it\/#organization","name":"De Riz Prosecco - Cantina in Conegliano Valdobbiadene","url":"https:\/\/proseccoderiz.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proseccoderiz.it\/#\/schema\/logo\/image\/","url":"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/logo-1.png","contentUrl":"https:\/\/proseccoderiz.it\/wp-content\/uploads\/2024\/08\/logo-1.png","width":494,"height":313,"caption":"De Riz Prosecco - Cantina in Conegliano Valdobbiadene"},"image":{"@id":"https:\/\/proseccoderiz.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/proseccoderiz.it\/en\/wp-json\/wp\/v2\/pages\/12205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proseccoderiz.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/proseccoderiz.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/proseccoderiz.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/proseccoderiz.it\/en\/wp-json\/wp\/v2\/comments?post=12205"}],"version-history":[{"count":4,"href":"https:\/\/proseccoderiz.it\/en\/wp-json\/wp\/v2\/pages\/12205\/revisions"}],"predecessor-version":[{"id":12209,"href":"https:\/\/proseccoderiz.it\/en\/wp-json\/wp\/v2\/pages\/12205\/revisions\/12209"}],"wp:attachment":[{"href":"https:\/\/proseccoderiz.it\/en\/wp-json\/wp\/v2\/media?parent=12205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}